{"id":4668,"date":"2019-05-02T15:58:13","date_gmt":"2019-05-02T13:58:13","guid":{"rendered":"https:\/\/www.kristensen.com\/?post_type=designers&#038;p=4668"},"modified":"2023-01-13T13:08:50","modified_gmt":"2023-01-13T12:08:50","slug":"studio-nur","status":"publish","type":"designers","link":"https:\/\/www.kristensen.com\/da\/designere\/studio-nur\/","title":{"rendered":"NUR DESIGN"},"menu_order":4,"template":"","class_list":["post-4668","designers","type-designers","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>NUR DESIGN - Kristensen &amp; Kristensen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.kristensen.com\/da\/designere\/studio-nur\/\" \/>\n<meta property=\"og:locale\" content=\"da_DK\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NUR DESIGN - Kristensen &amp; Kristensen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.kristensen.com\/da\/designere\/studio-nur\/\" \/>\n<meta property=\"og:site_name\" content=\"Kristensen &amp; Kristensen\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-13T12:08:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.kristensen.com\/da\/designere\/studio-nur\/\",\"url\":\"https:\/\/www.kristensen.com\/da\/designere\/studio-nur\/\",\"name\":\"NUR DESIGN - Kristensen &amp; Kristensen\",\"isPartOf\":{\"@id\":\"https:\/\/www.kristensen.com\/en\/#website\"},\"datePublished\":\"2019-05-02T13:58:13+00:00\",\"dateModified\":\"2023-01-13T12:08:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.kristensen.com\/da\/designere\/studio-nur\/#breadcrumb\"},\"inLanguage\":\"da-DK\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.kristensen.com\/da\/designere\/studio-nur\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.kristensen.com\/da\/designere\/studio-nur\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.kristensen.com\/da\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NUR DESIGN\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.kristensen.com\/en\/#website\",\"url\":\"https:\/\/www.kristensen.com\/en\/\",\"name\":\"Kristensen &amp; Kristensen\",\"description\":\"Just another WordPress site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.kristensen.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"da-DK\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"NUR DESIGN - Kristensen &amp; Kristensen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.kristensen.com\/da\/designere\/studio-nur\/","og_locale":"da_DK","og_type":"article","og_title":"NUR DESIGN - Kristensen &amp; Kristensen","og_url":"https:\/\/www.kristensen.com\/da\/designere\/studio-nur\/","og_site_name":"Kristensen &amp; Kristensen","article_modified_time":"2023-01-13T12:08:50+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.kristensen.com\/da\/designere\/studio-nur\/","url":"https:\/\/www.kristensen.com\/da\/designere\/studio-nur\/","name":"NUR DESIGN - Kristensen &amp; Kristensen","isPartOf":{"@id":"https:\/\/www.kristensen.com\/en\/#website"},"datePublished":"2019-05-02T13:58:13+00:00","dateModified":"2023-01-13T12:08:50+00:00","breadcrumb":{"@id":"https:\/\/www.kristensen.com\/da\/designere\/studio-nur\/#breadcrumb"},"inLanguage":"da-DK","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.kristensen.com\/da\/designere\/studio-nur\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.kristensen.com\/da\/designere\/studio-nur\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.kristensen.com\/da\/"},{"@type":"ListItem","position":2,"name":"NUR DESIGN"}]},{"@type":"WebSite","@id":"https:\/\/www.kristensen.com\/en\/#website","url":"https:\/\/www.kristensen.com\/en\/","name":"Kristensen &amp; Kristensen","description":"Just another WordPress site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.kristensen.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"da-DK"}]}},"_links":{"self":[{"href":"https:\/\/www.kristensen.com\/da\/wp-json\/wp\/v2\/designers\/4668","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kristensen.com\/da\/wp-json\/wp\/v2\/designers"}],"about":[{"href":"https:\/\/www.kristensen.com\/da\/wp-json\/wp\/v2\/types\/designers"}],"version-history":[{"count":5,"href":"https:\/\/www.kristensen.com\/da\/wp-json\/wp\/v2\/designers\/4668\/revisions"}],"predecessor-version":[{"id":10418,"href":"https:\/\/www.kristensen.com\/da\/wp-json\/wp\/v2\/designers\/4668\/revisions\/10418"}],"wp:attachment":[{"href":"https:\/\/www.kristensen.com\/da\/wp-json\/wp\/v2\/media?parent=4668"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}